{"id":12002,"date":"2022-03-02T15:55:14","date_gmt":"2022-03-02T20:55:14","guid":{"rendered":"https:\/\/colonce.edu.co\/web\/?p=12002"},"modified":"2022-09-16T15:56:49","modified_gmt":"2022-09-16T20:56:49","slug":"jornada-electoral-estudiantil-en-las-tres-sedes-de-la-institucion","status":"publish","type":"post","link":"https:\/\/colonce.edu.co\/web\/jornada-electoral-estudiantil-en-las-tres-sedes-de-la-institucion\/","title":{"rendered":"Izada de Bandera en conmemoraci\u00f3n a la Batalla de C\u00facuta"},"content":{"rendered":"<div dir=\"auto\">El d\u00eda de hoy se realiz\u00f3 la primer Izada de Bandera en conmemoraci\u00f3n a la Batalla de C\u00facuta a cargo de los estudiantes de sexto grado. Jornada Tarde sede principal.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El d\u00eda de hoy se realiz\u00f3 la primer Izada de Bandera en conmemoraci\u00f3n a la Batalla de C\u00facuta a cargo de los estudiantes de sexto grado. Jornada Tarde sede principal.<\/p>\n","protected":false},"author":1,"featured_media":12007,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[3471,3467],"tags":[],"class_list":["post-12002","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-izadas-de-bandera","category-noticias","post_format-post-format-gallery"],"_links":{"self":[{"href":"https:\/\/colonce.edu.co\/web\/wp-json\/wp\/v2\/posts\/12002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/colonce.edu.co\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/colonce.edu.co\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/colonce.edu.co\/web\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/colonce.edu.co\/web\/wp-json\/wp\/v2\/comments?post=12002"}],"version-history":[{"count":3,"href":"https:\/\/colonce.edu.co\/web\/wp-json\/wp\/v2\/posts\/12002\/revisions"}],"predecessor-version":[{"id":12013,"href":"https:\/\/colonce.edu.co\/web\/wp-json\/wp\/v2\/posts\/12002\/revisions\/12013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/colonce.edu.co\/web\/wp-json\/wp\/v2\/media\/12007"}],"wp:attachment":[{"href":"https:\/\/colonce.edu.co\/web\/wp-json\/wp\/v2\/media?parent=12002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/colonce.edu.co\/web\/wp-json\/wp\/v2\/categories?post=12002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/colonce.edu.co\/web\/wp-json\/wp\/v2\/tags?post=12002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}